{"id":547,"date":"2012-12-25T14:37:37","date_gmt":"2012-12-25T12:37:37","guid":{"rendered":"http:\/\/www.thomphotos.fr\/blog\/?p=547"},"modified":"2012-12-25T16:53:53","modified_gmt":"2012-12-25T14:53:53","slug":"les-mots-cles-de-2012","status":"publish","type":"post","link":"http:\/\/www.thomphotos.fr\/blog\/les-mots-cles-de-2012\/","title":{"rendered":"Les mots-cl\u00e9s de 2012"},"content":{"rendered":"<div id=\"fb_share_1\" style=\"float: right; margin-left: 10px;\"><a name=\"fb_share\" type=\"box_count\" share_url=\"http:\/\/www.thomphotos.fr\/blog\/les-mots-cles-de-2012\/\" href=\"http:\/\/www.facebook.com\/sharer.php\">Share<\/a><\/div><div><script src=\"http:\/\/static.ak.fbcdn.net\/connect.php\/js\/FB.Share\" type=\"text\/javascript\"><\/script><\/div><p>Cette ann\u00e9e encore, une petite compilations des mots-cl\u00e9s les plus particuliers que les gens ont tap\u00e9s pour arriver sur mon site. Ayant eu plus de visiteur, c&rsquo;est donc normal qu&rsquo;il y aille plus de mots-cl\u00e9 bizarres, pour notre plus grand bonheur <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/>.<\/p>\n<p>On commence doucement\u00a0 :<\/p>\n<p><em>\u00ab\u00a0peut on dire une sizaine d&rsquo;huitres\u00a0\u00bb<\/em><br \/>\nEn g\u00e9n\u00e9ral on dit une demi-douzaine, mais sizaine se disait aussi avant.<\/p>\n<p><em>\u00ab\u00a0carte sd vertigo ne passe pas dans appareil photo et camescope\u00a0\u00bb<\/em><br \/>\nN&rsquo;ayant jamais entendu parl\u00e9 de carte SD Vertigo, je me suis renseign\u00e9, c&rsquo;est une vieille marque (2008) qui faisait des cartes SD. Si cette carte ne fonctionne pas avec des appareils photos et vid\u00e9os r\u00e9cents, c&rsquo;est peut-\u00eatre qu&rsquo;elle est trop vieille (pas \u00e0 cause de la marque mais de son \u00e2ge ou d&rsquo;une mal-fonction). Il vaut donc mieux en changer. C&rsquo;est valable quelle que soit la marque de carte d&rsquo;ailleurs <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0anything\u00a0\u00bb<\/em><br \/>\nBen oui&#8230; \u00e0 vouloir tout chercher on tombe forc\u00e9ment sur mon site <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/><\/p>\n<p><em>\u00ab\u00a0lac cl\u00e9ment gel\u00e9\u00a0\u00bb<\/em><br \/>\nJe connais le lac L\u00e9man (ou lac de gen\u00e8ve) mais pas le lac cl\u00e9ment <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/><\/p>\n<p><em>\u00ab\u00a0tamron sigma canon nikon site:.fr\u00a0\u00bb<\/em><br \/>\nJ&rsquo;ai du mat\u00e9riel Canon et Sigma, mais pas de Nikon, de Tamron ou de Sony, ni de Pentax (les 2 qui manquent).<\/p>\n<p><em>\u00ab\u00a0menthe 500mm\u00a0\u00bb<\/em><br \/>\nUne photo de menthe avec un objectif 500mm ou de la menthe de 50cm de long ? Le premier cas n&rsquo;a pas trop d&rsquo;int\u00e9r\u00eat, le second est courant.<\/p>\n<p><em>\u00ab\u00a0lampe a dere\u00a0\u00bb<\/em><br \/>\nAlors l\u00e0&#8230; le pire c&rsquo;est que je l&rsquo;ai eu plusieurs fois dans l&rsquo;ann\u00e9e !<\/p>\n<p><em>\u00ab\u00a0y a t&rsquo;il des serpent a brive la gaillarde\u00a0\u00bb<\/em><br \/>\nComme un peu partout il y en a. \u00c0 Brive, vu la r\u00e9gion, ce seront surtout des vip\u00e8res et des couleuvres.<\/p>\n<p><em>\u00ab\u00a0division charlemagne bague\u00a0\u00bb<\/em><br \/>\nLa division Charlemagne&#8230; une division de SS durant la 2\u00e8me guerre mondiale ne comptant que des fran\u00e7ais volontaires (une des LVF, L\u00e9gion des Volontaires Fran\u00e7ais) qui se sont engag\u00e9s dans les SS nazies pour combattre les bolch\u00e9viques (en th\u00e9orie tout du moins). Une bien sombre p\u00e9riode pour l&rsquo;<br \/>\nEurope mais aussi le monde entier&#8230; J&rsquo;esp\u00e8re que nous n&rsquo;auront plus l&rsquo;occasion de vivre des horreurs pareilles ! Je n&rsquo;ai pas de photos de bagues de ce genre, en revanche une bague du roi Charlemagne, c&rsquo;est plus probable <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0carafe cam\u00e9e\u00a0\u00bb<\/em><br \/>\nUne carafe drogu\u00e9e ??<img decoding=\"async\" onclick=\"grin(':shock:');\" alt=\":shock:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_eek.gif\" \/><\/p>\n<p><em>\u00ab\u00a0paradis des photos des pandas roux\u00a0\u00bb<\/em><br \/>\nJe ne sais pas si c&rsquo;est le paradis mais j&rsquo;ai bien quelques photos de pandas roux sur mon site. J&rsquo;imagine qu&rsquo;il y a des sites avec bien plus de photos que \u00e7a (Certains en ont m\u00eame fait leur logo ! (Firefox)).<\/p>\n<p><em>\u00ab\u00a0la femme au xiieme siecle\u00a0\u00bb<\/em><br \/>\nUn peu d&rsquo;histoire&#8230; la femme au XII\u00e8me si\u00e8cle avait bien moins de droit qu&rsquo;aujourd&rsquo;hui et \u00e9tait vue comme soumise \u00e0 l&rsquo;homme (le p\u00e8re puis le mari).<\/p>\n<p><em>\u00ab\u00a0photo du singe marsupilamie noir le vrai\u00a0\u00bb<\/em><br \/>\nPour information : le Marsupilami (Marsu pour les intimes) est un animal invent\u00e9 de toutes pi\u00e8ces dans le cadre d&rsquo;une bande dessin\u00e9e (que je conseil).<br \/>\n<em><br \/>\n\u00ab\u00a0cache:vo7sb8o6svij:http:\/\/www.thomphotos.fr\/blog\/test-du-sigma-70-300mm\u00a0\u00bb<\/em><br \/>\nAttention, langage de geek ! Vu que mon article n&rsquo;a pas chang\u00e9 depuis sa r\u00e9daction, pas besoin d&rsquo;aller chercher dans le cache du navigateur l&rsquo;ancienne version <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0sniper pour dessiner\u00a0\u00bb<\/em><br \/>\nJe dois bien avouer que l\u00e0, je ne comprend pas ce que la personne cherchait&#8230; un sniper pour en faire un dessin ou dessiner avec un sniper ?<\/p>\n<p><em>\u00ab\u00a0chute dans la salle de bain\u00a0\u00bb<\/em><br \/>\ngnagnagna, le retour de la momie tout \u00e7a tout \u00e7a&#8230; \u00e7a fait mal quand m\u00eame ! <img decoding=\"async\" onclick=\"grin(':roll:');\" alt=\":roll:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_rolleyes.gif\" \/><\/p>\n<p><em>\u00ab\u00a02 loutres se tiennent main\u00a0\u00bb<\/em><br \/>\nC&rsquo;est mignon et j&rsquo;aurais bien voulu avoir une photo comme \u00e7a, ce n&rsquo;est malheureusement pas le cas, mais j&rsquo;ai quand m\u00eame quelques beaux clich\u00e9s <img decoding=\"async\" onclick=\"grin(':smile:');\" alt=\":smile:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_smile.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0http:\/\/ thomphotos;u7n.org.\u00a0\u00bb<\/em><br \/>\n\u00e7a, c&rsquo;est \u00e0 peu pr\u00e8s l&rsquo;adresse de mon ancien site qui n&rsquo;est plus fonctionnel depuis 2 ans d\u00e9j\u00e0.<\/p>\n<p><em>\u00ab\u00a0peinture explosive\u00a0\u00bb<\/em><br \/>\nHeu&#8230; de la peinture qui explose, c&rsquo;est&#8230; original&#8230; surtout quand elle est appliqu\u00e9e.<\/p>\n<p><em>\u00ab\u00a0myrm\u00e9cophage\u00a0\u00bb<\/em><br \/>\nJe ne le suis pas personnellement (je n&rsquo;en ai pas eu l&rsquo;occasion tout du moins). Mais je sais que certains aiment manger des fourmis (c&rsquo;est plus courant chez les singes ou d&rsquo;autres animaux que chez l&rsquo;homme quand m\u00eame.<\/p>\n<p><em>\u00ab\u00a0avenard mining\u00a0\u00bb<\/em><br \/>\nJe ne travail pas dans les mines (sauf dans Minecraft <img decoding=\"async\" onclick=\"grin(':lol:');\" alt=\":lol:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_lol.gif\" \/> ).<\/p>\n<p><em>\u00ab\u00a0diff\u00e9rents plans d&rsquo;une photographie\u00a0\u00bb<\/em><br \/>\nOn me l&rsquo;a souvent demand\u00e9 cette ann\u00e9e, je vais donc (enfin <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> ) y r\u00e9pondre : <a href=\"http:\/\/www.thomphotos.fr\/index.php?page=cours_videos&amp;PHPSESSID=h6bukng3i0m03mp0t4pgioqn16#ancre3\">ce sont les m\u00eames qu&rsquo;en vid\u00e9o !<\/a><\/p>\n<p><em>\u00ab\u00a0\u00a0\u00bbmessier 35\u00a0\u00bb or \u00ab\u00a0ngc 2168&Prime; amas ouvert\u00a0\u00bb<\/em><br \/>\nEn voil\u00e0 un qui sait ce qu&rsquo;il veut, voici donc M35 en photo :<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"M35\" src=\"http:\/\/www.thomphotos.fr\/images\/astronomie\/M35.jpg\" width=\"800\" height=\"562\" \/><br \/>\n<em><br \/>\n\u00ab\u00a0registre du commerce thomas uldry avenard\u00a0\u00bb<\/em><br \/>\nOui oui, je suis inscrit, voici m\u00eame mon num\u00e9ro de registre pour ceux qui ne me croiraient pas : CHE-149.638.078. Ce num\u00e9ro est visible par tous sur internet, il suffit de le chercher au bon endroit <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0buisson dog\u00a0\u00bb<\/em><br \/>\nEn fran\u00e7ais : chien de buisson, dans le top 10 des mots-cl\u00e9s les plus fr\u00e9quents, le voici maintenant en anglais !<\/p>\n<p><em>\u00ab\u00a0bonne nuit photo voiture\u00a0\u00bb<\/em><br \/>\nBonne nuit \u00e0 vous aussi ! (ha non, Joyeux No\u00ebl ! <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> )<\/p>\n<p><em>\u00ab\u00a0rayon de dieu\u00a0\u00bb<\/em><br \/>\nNon non, ce n&rsquo;est qu&rsquo;un rayon de soleil en HDR (sauf si votre dieu s&rsquo;appelle R\u00e2, \u00e0 ce moment-l\u00e0 oui, c&rsquo;est un rayon de dieu (R\u00e2 est le dieu-soleil dans la mythologie \u00e9gyptienne)).<\/p>\n<p><em>\u00ab\u00a0numeros de telephone pour prendre des cour de photographe a muret\u00a0\u00bb<\/em><br \/>\nJe ne connais pas du tout ce num\u00e9ro, en revanche je donne moi aussi des cours sur versoix\/gen\u00e8ve (ainsi qu&rsquo;un peu de th\u00e9orie sur mon site).<\/p>\n<p><em>\u00ab\u00a0photo oiseaux regles composition 1\/3 ou centrer\u00a0\u00bb<\/em><br \/>\nComme pour n&rsquo;importe quelle photo, il vaut mieux respecter la r\u00e8gle des tiers. Sauf que&#8230; pour une question de rapidit\u00e9 d&rsquo;action, au d\u00e9but, il vaut mieux centrer lors de la prise de vue et recadrer apr\u00e8s sur l&rsquo;ordinateur <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0animal gel\u00e9 temp\u00eate de verglas\u00a0\u00bb<\/em><br \/>\nDes voitures, des arbres, les quais, un mannequin (moi\u00a0 <img decoding=\"async\" onclick=\"grin(':roll:');\" alt=\":roll:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_rolleyes.gif\" \/><img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> ) mais pas d&rsquo;animaux (pas \u00e0 ma connaissance (mise \u00e0 part des animaux \u00e0 sang froid ou insectes)).<\/p>\n<p><em>\u00ab\u00a0je cherche un fond de noel pour y rajouter une photos\u00a0\u00bb<\/em><br \/>\nMoi je cherche un billet gagnant pour le jackpot de l\u2019euro-million, vous auriez pas \u00e7a ? <img decoding=\"async\" onclick=\"grin(':roll:');\" alt=\":roll:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_rolleyes.gif\" \/> J&rsquo;ai plusieurs photos qui pourraient correspondre, mais faut bien que je mange, que je paye mes imp\u00f4ts, etc etc&#8230; comme tout le monde. sinon vous pouvez vous contentez des photos sur le site, elles sont petites et avec ma signature mais bon, on n&rsquo;a rien sans rien <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0sapin de noel de mineraux\u00a0\u00bb<\/em><br \/>\nAlors l\u00e0&#8230; je sais pas qui c&rsquo;est qui cherchait \u00e7a, mais pour le coup je trouve l&rsquo;id\u00e9e g\u00e9niale, je testerai l&rsquo;an prochain ! (Voir cette ann\u00e9e avec de la chance.)<\/p>\n<p><em>\u00ab\u00a0vis\u00e9e m14\u00a0\u00bb<\/em><br \/>\nJe n&rsquo;ai qu&rsquo;un M14 Socom airsoft, pas de vrai, d\u00e9sol\u00e9. Mais je ferai une photo du genre si \u00e7a peut en int\u00e9resser certains. Faut pas croire hein, j&rsquo;\u00e9coute quand m\u00eame mes visiteurs ^^.<\/p>\n<p><em>\u00ab\u00a0chocolat apple\u00a0\u00bb<\/em><br \/>\nSi Apple se mets \u00e0 faire du chocolat, on aura le chocolat le plus cher du monde et il faudra demander l&rsquo;autorisation \u00e0 big brother avant d&rsquo;en manger (oui, je troll et j&rsquo;en suis fier <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> !).<\/p>\n<p><em>\u00ab\u00a0\u00e9volution l\u00e9gume\u00a0\u00bb<\/em><br \/>\nEn timelapse ? C&rsquo;est pr\u00e9vu <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0exemples de photos animali\u00e8res filtre de renforcement de nettet\u00e9\u00a0\u00bb<\/em><br \/>\nJe n&rsquo;ai pas de photos de ce genre, n&rsquo;ayant pas le filtre en question. Mais pour information, c&rsquo;est un filtre jaune qu&rsquo;il faut (augmentation contrastes et nettet\u00e9).<\/p>\n<p><em>\u00ab\u00a0images of the place with water instead of streets\u00a0\u00bb<\/em><br \/>\nMise \u00e0 part Venise je ne vois pas quelle ville pourrait avoir des chemins d&rsquo;eau \u00e0 la place de rues&#8230;<\/p>\n<p><em>\u00ab\u00a0vieux photocopierus\u00a0\u00bb<\/em><br \/>\nLe revoil\u00e0 lui ?! D\u00e9j\u00e0 pr\u00e9sent l&rsquo;an pass\u00e9, il revient&#8230; \u00e0 l&rsquo;ann\u00e9e prochaine donc <img decoding=\"async\" onclick=\"grin(':lol:');\" alt=\":lol:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_lol.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0blog gopro\u00a0\u00bb<\/em><br \/>\nJ&rsquo;ai une GoPro, j&rsquo;ai un blog, j&rsquo;ai pr\u00e9vu d&rsquo;utiliser ma GoPro&#8230; mais mon blog n&rsquo;est pas d\u00e9di\u00e9 \u00e0 cet appareil <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0camera professionnelle detruite\u00a0\u00bb<\/em><br \/>\nNaonnnnnn ! Y&rsquo;a bien que DigitalRev \u00e0 le faire \u00e7a.<\/p>\n<p><em>\u00ab\u00a0didier filonczuk\u00a0\u00bb<\/em><br \/>\nHeu&#8230; je ne crois pas en avoir parl\u00e9 sur mon site pourtant une personne est tomb\u00e9e sur mon site en cherchant Didier&#8230; Coucou \u00e0 lui d&rsquo;ailleurs, ainsi qu&rsquo;\u00e0 Romuald et aux copains des 3 \u00e9pis \u00e0 Brive ! J&rsquo;arrive d&rsquo;ici quelques jours pour No\u00ebl, je passerai vous voir <img decoding=\"async\" onclick=\"grin(':grin:');\" alt=\":grin:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_biggrin.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0martien\u00a0\u00bb<\/em><br \/>\nHeu, les petits hommes verts ou ceux de Mars attack ?<\/p>\n<p>Nous avons maintenant une partie consacr\u00e9e \u00e0 Koala-Jones, son heure de gloire (ou pas ?) :<\/p>\n<p><em>\u00ab\u00a0boutique en ligne de peluche koala\u00a0\u00bb<\/em><br \/>\nL&rsquo;id\u00e9e est dans un coin de ma t\u00eate, mais il n&rsquo;y a pas assez de demandes(pour le moment ?) pour que je vende des peluches de Koala-Jones.<\/p>\n<p><em>\u00ab\u00a0kodak koala\u00a0\u00bb<\/em><br \/>\nKoala-Jones m&rsquo;aurait chourav\u00e9 mon vieux instamatics ?<\/p>\n<p><em>\u00ab\u00a0le koala qui disait des gros mots\u00a0\u00bb<\/em><br \/>\nOooh il en dit oui, mais pas devant les lectrices <img decoding=\"async\" onclick=\"grin(':razz:');\" alt=\":razz:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_razz.gif\" \/> .<\/p>\n<p>Partie incompr\u00e9hension maintenant :<\/p>\n<p><em>\u00ab\u00a0meuhmeuh\u00a0\u00bb<\/em><br \/>\nJ&rsquo;ai h\u00e9sit\u00e9 \u00e0 faire une partie onomatop\u00e9e. Gruiiikkkkk !<\/p>\n<p><em>\u00ab\u00a0mouton beh beh\u00a0\u00bb<\/em><br \/>\nDans la lign\u00e9e de celui du dessus&#8230; d\u00e9cid\u00e9ment c&rsquo;est la basse-cour ici. C\u00f4t c\u00f4t Codeeeeeeeeet !<\/p>\n<p><em>\u00ab\u00a0\u0639\u062f\u0633\u0647 500-mm 150\u00a0\u00bb<\/em><br \/>\nJ&rsquo;ai l&rsquo;impression qu&rsquo;il y a des personnes parlants arabe (je crois ?) qui viennent sur mon site, c&rsquo;est cool, \u00e7a montre que je suis pass\u00e9 \u00e0 l&rsquo;international youhou !<\/p>\n<p><em>\u00ab\u00a0\u0e23\u0e35\u0e27\u0e34\u0e27150-500mm f5-6.3 apo dg os hsm\u00a0\u00bb<\/em><br \/>\nL\u00e0 je crois que c&rsquo;est du vietnamien (une langue du sud-est asiatique en tout cas). Je suis en passe de conqu\u00e9rir le monnnnndddeeeee !<\/p>\n<p><em>\u00ab\u00a0calice holy mass silver buy\u00a0\u00bb<\/em><br \/>\nHeu.. un anglophone veut acheter le saint Graal ou quelque chose du genre j&rsquo;ai l&rsquo;impression&#8230; malheureusement je ne l&rsquo;ai pas <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0l\u00e9zard bleu {22,20,3,2,2,1x}\u00a0\u00bb<\/em><br \/>\nUn l\u00e9zard bleu dans une matrice ? Les maths sont un peu loin dans ma m\u00e9moire, d\u00e9sol\u00e9 ^^.<\/p>\n<p><em>\u00ab\u00a0lemanete mouth\u00a0\u00bb<\/em><br \/>\n\u00c0 tes souhaits ! Si quelqu&rsquo;un a une traduction, je suis preneur <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0kenavo african plants\u00a0\u00bb<\/em><br \/>\nHmmm&#8230; K\u00e9navo = \u00ab\u00a0salut\u00a0\u00bb en breton, je n&rsquo;ai jamais entendu parl\u00e9 d&rsquo;une plante (africaine ou pas) qui portait ce nom.<\/p>\n<p><em>\u00ab\u00a0nous voici projet\u00e9s\u00a0\u00bb<\/em><br \/>\nDans la 5\u00e8me dimension avec les mots-cl\u00e9s qui vont suivre&#8230; jeunes enfants et \u00e2mes sensibles s&rsquo;abstenir.<\/p>\n<p><em>\u00ab\u00a0filles blonde metro\u00a0\u00bb<\/em><br \/>\nJe donne le th\u00e8me de mani\u00e8re soft ^^. (\u00e7a fait assez stalker ce genre de recherche&#8230;)<\/p>\n<p><em>\u00ab\u00a0photographe professionnel porn\u00a0\u00bb<\/em><br \/>\nEt c&rsquo;est parti&#8230; les pervers de tous poils ont d\u00e9barqu\u00e9s sur mon site ! Planquez les jeunes vierges et les jeunes <img decoding=\"async\" onclick=\"grin(':twisted:');\" alt=\":twisted:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_twisted.gif\" \/> . Pour info, je n&rsquo;ai jamais fais de ce genre de photos !<\/p>\n<p><em>\u00ab\u00a0porno photography\u00a0\u00bb<\/em><br \/>\nNon non, toujours pas, pas plus en anglais qu&rsquo;en fran\u00e7ais d&rsquo;ailleurs ^^.<\/p>\n<p><em>\u00ab\u00a0macro pornography\u00a0\u00bb<\/em><br \/>\nHeuuuu&#8230; le sexe chez les insectes ? Rh\u00f4 les coquins <img decoding=\"async\" onclick=\"grin(':oops:');\" alt=\":oops:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_redface.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0ponr porno\u00a0\u00bb<\/em><br \/>\nToujours pas ! Ils y tiennent \u00e0 avoir des photos de cul sur mon site hein ? <img decoding=\"async\" onclick=\"grin(':lol:');\" alt=\":lol:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_lol.gif\" \/><\/p>\n<p><em>\u00ab\u00a0baton moldave porno\u00a0\u00bb<\/em><br \/>\nBWAHAAHAHAHA ! hum&#8230; pardon&#8230; j&rsquo;ai ris&#8230; je sors <img decoding=\"async\" onclick=\"grin(':arrow:');\" alt=\":arrow:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_arrow.gif\" \/><\/p>\n<p><em>\u00ab\u00a0bibitte verte\u00a0\u00bb<\/em><br \/>\nSi elle est verte, c&rsquo;est qu&rsquo;il y a un petit probl\u00e8me non ?<\/p>\n<p><em>\u00ab\u00a0photo homme de puis3 ans dans un caveau\u00a0\u00bb<\/em><br \/>\n\u00e7a fait assez d\u00e9lire sado-maso (SM) \u00e7a&#8230; enfin.. chacun ses d\u00e9lires hein <img decoding=\"async\" onclick=\"grin(':roll:');\" alt=\":roll:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_rolleyes.gif\" \/> comme on dit \u00ab\u00a0les coups et les douleurs\u00a0\u00bb <img decoding=\"async\" onclick=\"grin(':lol:');\" alt=\":lol:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_lol.gif\" \/> .<\/p>\n<p><em>\u00ab\u00a0baiser chameau dans un zoo\u00a0\u00bb<\/em><br \/>\nY&rsquo;a vraiment des tordus <img decoding=\"async\" onclick=\"grin(':evil:');\" alt=\":evil:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_evil.gif\" \/> .<\/p>\n<p><strong>Et le mot-cl\u00e9 Number one le voici :<\/strong><br \/>\n<em>\u00ab\u00a0monstruouse straopn\u00a0\u00bb<\/em><\/p>\n<p>No comment ! (Enfin si, juste une petite info, traduit, \u00e7a donne : \u00ab\u00a0Monstrueux godemichet-ceinture\u00a0\u00bb&#8230; quand je vous le dis que y&rsquo;a des tordus ! <img decoding=\"async\" onclick=\"grin(':lol:');\" alt=\":lol:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_lol.gif\" \/> )<\/p>\n<p>Et voil\u00e0, la petite r\u00e9trospective 2012 des mots-cl\u00e9s bizarres et tordus. Y&rsquo;a du niveau, mais je suis s\u00fbr que \u00e7a serra encore mieux\/pire en 2013, je vous fais confiance pour \u00e7a <img decoding=\"async\" onclick=\"grin(':mrgreen:');\" alt=\":mrgreen:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_mrgreen.gif\" \/> .<\/p>\n<p>N&rsquo;oubliez pas le concours, c&rsquo;est le dernier jour demain, d\u00e9p\u00eachez-vous <img decoding=\"async\" onclick=\"grin(';-)');\" alt=\";-)\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_wink.gif\" \/> .<\/p>\n<p>Et <strong>JOYEUX NO\u00cbL<\/strong> encore une fois ! <img decoding=\"async\" onclick=\"grin(':smile:');\" alt=\":smile:\" src=\"http:\/\/www.thomphotos.fr\/blog\/wp-includes\/images\/smilies\/icon_smile.gif\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ShareCette ann\u00e9e encore, une petite compilations des mots-cl\u00e9s les plus particuliers que les gens ont tap\u00e9s pour arriver sur mon site. Ayant eu plus de visiteur, c&rsquo;est donc normal qu&rsquo;il y aille plus de mots-cl\u00e9 bizarres, pour notre plus grand &hellip; <a href=\"http:\/\/www.thomphotos.fr\/blog\/les-mots-cles-de-2012\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,40,57],"tags":[108,192,195],"class_list":["post-547","post","type-post","status-publish","format-standard","hentry","category-koala-jones-2","category-ma-pomme","category-site-et-blog","tag-koala-jones","tag-ma-pomme","tag-site-et-blog"],"_links":{"self":[{"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/posts\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/comments?post=547"}],"version-history":[{"count":3,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/posts\/547\/revisions"}],"predecessor-version":[{"id":549,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/posts\/547\/revisions\/549"}],"wp:attachment":[{"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/media?parent=547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/categories?post=547"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.thomphotos.fr\/blog\/wp-json\/wp\/v2\/tags?post=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}